{"id":2460,"date":"2022-11-15T08:21:47","date_gmt":"2022-11-15T13:21:47","guid":{"rendered":"https:\/\/www.marshall.edu\/academic-affairs\/?post_type=employee&#038;p=2460"},"modified":"2026-04-21T08:05:18","modified_gmt":"2026-04-21T12:05:18","slug":"cicero-fain","status":"publish","type":"employee","link":"https:\/\/www.marshall.edu\/academic-affairs\/profile\/cicero-fain\/","title":{"rendered":"Dr. Cicero M. Fain, IIII"},"menu_order":41,"template":"","meta":{"_acf_changed":false},"department":[40],"class_list":["post-2460","employee","type-employee","status-publish","hentry","department-academic-affairs"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.marshall.edu\/academic-affairs\/wp-json\/wp\/v2\/employee\/2460","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.marshall.edu\/academic-affairs\/wp-json\/wp\/v2\/employee"}],"about":[{"href":"https:\/\/www.marshall.edu\/academic-affairs\/wp-json\/wp\/v2\/types\/employee"}],"version-history":[{"count":11,"href":"https:\/\/www.marshall.edu\/academic-affairs\/wp-json\/wp\/v2\/employee\/2460\/revisions"}],"predecessor-version":[{"id":3359,"href":"https:\/\/www.marshall.edu\/academic-affairs\/wp-json\/wp\/v2\/employee\/2460\/revisions\/3359"}],"wp:attachment":[{"href":"https:\/\/www.marshall.edu\/academic-affairs\/wp-json\/wp\/v2\/media?parent=2460"}],"wp:term":[{"taxonomy":"department","embeddable":true,"href":"https:\/\/www.marshall.edu\/academic-affairs\/wp-json\/wp\/v2\/department?post=2460"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}