{"id":1297,"date":"2024-06-07T10:08:11","date_gmt":"2024-06-07T15:08:11","guid":{"rendered":"https:\/\/www.marshall.edu\/history\/?post_type=employee&#038;p=1297"},"modified":"2024-12-20T10:21:39","modified_gmt":"2024-12-20T15:21:39","slug":"greta-rensenbrink","status":"publish","type":"employee","link":"https:\/\/www.marshall.edu\/history\/profile\/greta-rensenbrink\/","title":{"rendered":"Greta Rensenbrink"},"menu_order":-950,"template":"","meta":{"_acf_changed":false},"department":[7],"class_list":["post-1297","employee","type-employee","status-publish","hentry","department-history"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.marshall.edu\/history\/wp-json\/wp\/v2\/employee\/1297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.marshall.edu\/history\/wp-json\/wp\/v2\/employee"}],"about":[{"href":"https:\/\/www.marshall.edu\/history\/wp-json\/wp\/v2\/types\/employee"}],"version-history":[{"count":5,"href":"https:\/\/www.marshall.edu\/history\/wp-json\/wp\/v2\/employee\/1297\/revisions"}],"predecessor-version":[{"id":1470,"href":"https:\/\/www.marshall.edu\/history\/wp-json\/wp\/v2\/employee\/1297\/revisions\/1470"}],"wp:attachment":[{"href":"https:\/\/www.marshall.edu\/history\/wp-json\/wp\/v2\/media?parent=1297"}],"wp:term":[{"taxonomy":"department","embeddable":true,"href":"https:\/\/www.marshall.edu\/history\/wp-json\/wp\/v2\/department?post=1297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}